{"id":2217,"date":"2021-04-12T09:57:34","date_gmt":"2021-04-12T12:57:34","guid":{"rendered":"https:\/\/isfd82-bue.infd.edu.ar\/sitio\/?p=2217"},"modified":"2021-04-12T09:57:34","modified_gmt":"2021-04-12T12:57:34","slug":"ingresantes-2021-ingreso-al-campus","status":"publish","type":"post","link":"https:\/\/isfd82-bue.infd.edu.ar\/sitio\/ingresantes-2021-ingreso-al-campus\/","title":{"rendered":"Ingresantes 2021- Ingreso al Campus"},"content":{"rendered":"<p>Estimadxs estudiantes<\/p>\n<p>En el transcurso del d\u00eda de hoy, (luego del mediod\u00eda), estar\u00e1n recibiendo paulatinamente <span style=\"color: #ff6600;\"><strong>en sus correos electr\u00f3nicos un aviso de la Plataforma del Instituto para ingresar al Campus.<\/strong><\/span><\/p>\n<p><strong>Este proceso ser\u00e1 masivo<\/strong> por lo cual puede haber por problemas de conectividad algunos errores, NO SE PREOCUPEN,\u00a0 luego pasaremos paso a paso para ingresar Manualmente o un correo electr\u00f3nico para RECLAMOS\u00a0 a partir de ma\u00f1ana martes 13 de abril.<\/p>\n<p>Iremos comunicando m\u00e1s informaciones relacionados con <strong>el ACCESO<\/strong>,\u00a0 mientras tanto les sugerimos pasar en limpio las Bit\u00e1coras , dado que la primer clase del Campus, estar\u00e1 comprendiendo esos registros.<\/p>\n<p>Hasta la pr\u00f3xima Informaci\u00f3n<\/p>\n<p>Nos seguimos cuidando!<\/p>\n<p>Equipo Directivo<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimadxs estudiantes En el transcurso del d\u00eda de hoy, (luego del mediod\u00eda), estar\u00e1n recibiendo paulatinamente en sus correos electr\u00f3nicos un aviso de la Plataforma del Instituto para ingresar al Campus. Este proceso ser\u00e1 masivo por lo cual puede haber por problemas de conectividad algunos errores, NO SE PREOCUPEN,\u00a0 luego pasaremos paso a paso para ingresar &#8230; <a title=\"Ingresantes 2021- Ingreso al Campus\" class=\"read-more\" href=\"https:\/\/isfd82-bue.infd.edu.ar\/sitio\/ingresantes-2021-ingreso-al-campus\/\" aria-label=\"More on Ingresantes 2021- Ingreso al Campus\">[+]<\/a><\/p>\n","protected":false},"author":1341,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/isfd82-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/2217"}],"collection":[{"href":"https:\/\/isfd82-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/isfd82-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/isfd82-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/users\/1341"}],"replies":[{"embeddable":true,"href":"https:\/\/isfd82-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/comments?post=2217"}],"version-history":[{"count":1,"href":"https:\/\/isfd82-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/2217\/revisions"}],"predecessor-version":[{"id":2218,"href":"https:\/\/isfd82-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/2217\/revisions\/2218"}],"wp:attachment":[{"href":"https:\/\/isfd82-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/media?parent=2217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/isfd82-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/categories?post=2217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/isfd82-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/tags?post=2217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}